{"id":43578,"date":"2025-08-28T07:20:55","date_gmt":"2025-08-28T12:20:55","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=43578"},"modified":"2025-08-28T07:20:55","modified_gmt":"2025-08-28T12:20:55","slug":"ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/","title":{"rendered":"Ibagu\u00e9, Negocios &#038; Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n"},"content":{"rendered":"<p>Con un emotivo acto protocolario, un desfile de alto nivel y la entrega de reconocimientos a quienes han acompa\u00f1ado su historia, la feria Ibagu\u00e9, Negocios &amp; Moda \u2013 IN&amp;M 2025 inaugur\u00f3 oficialmente su edici\u00f3n n\u00famero 15, consolid\u00e1ndose como uno de los eventos m\u00e1s importantes del sistema moda en Colombia.<\/p>\n<p>Con la presencia de autoridades locales, empresarios, dise\u00f1adores y medios de comunicaci\u00f3n, la feria Ibagu\u00e9, Negocios &amp; Moda \u2013 IN&amp;M 2025 dio apertura oficial a su edici\u00f3n n\u00famero 15, destacando el proceso de evoluci\u00f3n que ha consolidado al Tolima como un referente de la moda nacional.<\/p>\n<p>El evento inaugural tuvo como gran apertura el desfile de Polite, marca internacional de lujo dirigida por el dise\u00f1ador colombo-espa\u00f1ol Carlos Polite, quien present\u00f3 su m\u00e1s reciente colecci\u00f3n en un montaje que uni\u00f3 moda, arte y m\u00fasica en el Conservatorio del Tolima. Al finalizar su pasarela, Polite recibi\u00f3 la estatuilla Costurera de la Moda, un reconocimiento especial que rinde homenaje a quienes han dedicado su vida a construir con sus manos las prendas que dan identidad y valor a esta industria.<\/p>\n<p>Durante su intervenci\u00f3n, Julio Mendoza, director de Cormoda, se\u00f1al\u00f3: \u201cIbagu\u00e9, Negocios y Moda cumple 15 a\u00f1os siendo art\u00edfice de un proceso de transformaci\u00f3n productiva, pasando de representar un sector maquilador a consolidar uno innovador, con propuestas avanzadas en dise\u00f1o y desarrollo de marca, cada vez m\u00e1s competitivo en el mercado nacional\u201d.<\/p>\n<p>Por su parte, la gobernadora del Tolima, Adriana Magali Matiz, destac\u00f3 el papel del sector moda en la econom\u00eda y la identidad regional. \u201cEl talento de los tolimenses nos permite demostrar que estamos a la altura de grandes escenarios nacionales e internacionales. IN&amp;M es la muestra de que cuando trabajamos juntos, el Tolima se transforma y se proyecta con esperanza hacia el futuro\u201d, se\u00f1al\u00f3 la mandataria.<\/p>\n<p>En el marco de la ceremonia, se entregaron reconocimientos a Cormoda y a diferentes entidades aliadas que han acompa\u00f1ado y apoyado la feria a lo largo de estos a\u00f1os, resaltando el trabajo articulado entre el sector p\u00fablico y privado para impulsar la internacionalizaci\u00f3n del Sistema Moda en el Tolima.<\/p>\n<p>All\u00ed, la alcaldesa de Ibagu\u00e9, Johana Aranda, aprovech\u00f3 para resaltar el talento de los ibaguere\u00f1os que conforman este gremio: \u201cVamos a mostrar lo mejor en la industria textilera, esperamos que todos nos acompa\u00f1en. Estaremos en el centro comercial Multicentro en donde todos los tolimenses est\u00e1n invitados a ver la creatividad y la gran costura que hoy tiene nuestra ciudad, los dise\u00f1adores y los emprendedores\u201d.<\/p>\n<p>La programaci\u00f3n de IN&amp;M continuar\u00e1 hasta el pr\u00f3ximo s\u00e1bado 30 de agosto con pasarelas, agenda acad\u00e9mica, rueda de negocios y una muestra empresarial con 94 expositores. \u201cGracias a todos por ser parte de este sue\u00f1o. Desde Cormoda reiteramos nuestro compromiso y entrega para seguir construyendo un futuro promisorio para los tolimenses, convencidos de que la moda no es solo una industria, sino una expresi\u00f3n de identidad, creatividad y esperanza que nos proyecta hacia el mundo\u201d, concluy\u00f3 Mendoza.<\/p>\n<p>Ibagu\u00e9, Negocios &amp; Moda es un evento patrocinado por la Gobernaci\u00f3n del Tolima, organizado por Cormoda y cuenta con el apoyo de la C\u00e1mara de Comercio de Ibagu\u00e9 y la Alcald\u00eda de Ibagu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un emotivo acto protocolario, un desfile de alto nivel y la entrega de reconocimientos a quienes han acompa\u00f1ado su historia, la feria Ibagu\u00e9, Negocios &amp; Moda \u2013 IN&amp;M 2025 inaugur\u00f3 oficialmente su edici\u00f3n n\u00famero 15, consolid\u00e1ndose como uno de los eventos m\u00e1s importantes del sistema moda en Colombia. Con<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":43579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[31],"tags":[],"class_list":["entry","author-diegoaguirre","post-43578","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entretenimiento"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibagu\u00e9, Negocios &amp; Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibagu\u00e9, Negocios &amp; Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"Con un emotivo acto protocolario, un desfile de alto nivel y la entrega de reconocimientos a quienes han acompa\u00f1ado su historia, la feria Ibagu\u00e9, Negocios &amp; Moda \u2013 IN&amp;M 2025 inaugur\u00f3 oficialmente su edici\u00f3n n\u00famero 15, consolid\u00e1ndose como uno de los eventos m\u00e1s importantes del sistema moda en Colombia. ConContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T12:20:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\",\"name\":\"Ibagu\u00e9, Negocios & Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-08-28T12:20:55+00:00\",\"dateModified\":\"2025-08-28T12:20:55+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ibagu\u00e9, Negocios &#038; Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibagu\u00e9, Negocios & Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Ibagu\u00e9, Negocios & Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region","og_description":"Con un emotivo acto protocolario, un desfile de alto nivel y la entrega de reconocimientos a quienes han acompa\u00f1ado su historia, la feria Ibagu\u00e9, Negocios &amp; Moda \u2013 IN&amp;M 2025 inaugur\u00f3 oficialmente su edici\u00f3n n\u00famero 15, consolid\u00e1ndose como uno de los eventos m\u00e1s importantes del sistema moda en Colombia. ConContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/","og_site_name":"Ciudad y Region","article_published_time":"2025-08-28T12:20:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png","type":"image\/png"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/","name":"Ibagu\u00e9, Negocios & Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1","datePublished":"2025-08-28T12:20:55+00:00","dateModified":"2025-08-28T12:20:55+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/ibague-negocios-moda-celebro-su-acto-inaugural-con-homenaje-a-15-anos-de-transformacion\/entretenimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Ibagu\u00e9, Negocios &#038; Moda celebr\u00f3 su acto inaugural con homenaje a 15 a\u00f1os de transformaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/2-2.png?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-bkS","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43578"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=43578"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43578\/revisions"}],"predecessor-version":[{"id":43580,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43578\/revisions\/43580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/43579"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=43578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=43578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=43578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}