{"id":43226,"date":"2025-08-25T08:11:53","date_gmt":"2025-08-25T13:11:53","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=43226"},"modified":"2025-08-25T08:11:53","modified_gmt":"2025-08-25T13:11:53","slug":"cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/","title":{"rendered":"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda"},"content":{"rendered":"<p>La jornada recreativa y deportiva integr\u00f3 a las familias en el mes de las cometas en el Parque Deportivo.<\/p>\n<p>El Parque Deportivo fue epicentro del Festival del Aire 2025, un certamen que reuni\u00f3 a la comunidad en general en una jornada llena de sonrisas, diversi\u00f3n, esparcimiento y ante todo integraci\u00f3n familiar con distintas actividades l\u00fadicas y recreativas en torno a las cometas.<\/p>\n<p>Fueron cerca de tres mil personas quienes desde tempranas horas de la ma\u00f1ana de este domingo 24 de agosto aceptaron la invitaci\u00f3n de la Alcald\u00eda de Ibagu\u00e9 y el Gestor Social, Juan Arturo Guti\u00e9rrez, quienes extendieron la invitaci\u00f3n a distintas empresas privadas y se vincularon a la actividad.<\/p>\n<blockquote><p>\u201cNo se imaginan la felicidad que tenemos al llegar a estos espacios, nada mejor que salir con aquellos que m\u00e1s queremos y compartir un momento con ellos, muchas veces por temas laborales no podemos hacer esto de manera seguida\u201d, dijo Carlos Castillo, padre de familia.<\/p><\/blockquote>\n<p>Desde el Instituto Municipal para el Deporte y la Recreaci\u00f3n, Imdri, se habilitaron los circuitos recreativos que comprend\u00edan Gimnasio de la Ni\u00f1ez, Escuelas de Talentos, Actividad F\u00edsica Musicalizada entre otras, donde los ni\u00f1os, ni\u00f1as y adolescentes, disfrutaron de la programaci\u00f3n.<\/p>\n<blockquote><p>\u201cMis hijos la han pasado muy feliz, llegaron aqu\u00ed a volar cometa, pero han aprovechado toda esa oferta que desde la Administraci\u00f3n les han dispuesto para que la pasen genial y ante todo motivados en un lindo escenario\u201d, manifest\u00f3 Catalina Santos, asistente a la actividad.<\/p><\/blockquote>\n<p>As\u00ed las cosas, se confirma una vez m\u00e1s que la propuesta \u2018Ibagu\u00e9 Casa del Deporte en Colombia\u2019 hoy no solamente promueve actividades con federaciones y organismos deportivos, tambi\u00e9n le abre las puertas a la ciudadan\u00eda con este tipo de cert\u00e1menes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jornada recreativa y deportiva integr\u00f3 a las familias en el mes de las cometas en el Parque Deportivo. El Parque Deportivo fue epicentro del Festival del Aire 2025, un certamen que reuni\u00f3 a la comunidad en general en una jornada llena de sonrisas, diversi\u00f3n, esparcimiento y ante todo integraci\u00f3n<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":43227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[14],"tags":[],"class_list":["entry","author-diegoaguirre","post-43226","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ibague"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"La jornada recreativa y deportiva integr\u00f3 a las familias en el mes de las cometas en el Parque Deportivo. El Parque Deportivo fue epicentro del Festival del Aire 2025, un certamen que reuni\u00f3 a la comunidad en general en una jornada llena de sonrisas, diversi\u00f3n, esparcimiento y ante todo integraci\u00f3nContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-25T13:11:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\",\"name\":\"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-08-25T13:11:53+00:00\",\"dateModified\":\"2025-08-25T13:11:53+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/","og_locale":"es_ES","og_type":"article","og_title":"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region","og_description":"La jornada recreativa y deportiva integr\u00f3 a las familias en el mes de las cometas en el Parque Deportivo. El Parque Deportivo fue epicentro del Festival del Aire 2025, un certamen que reuni\u00f3 a la comunidad en general en una jornada llena de sonrisas, diversi\u00f3n, esparcimiento y ante todo integraci\u00f3nContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/","og_site_name":"Ciudad y Region","article_published_time":"2025-08-25T13:11:53+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/","name":"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1","datePublished":"2025-08-25T13:11:53+00:00","dateModified":"2025-08-25T13:11:53+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cerca-de-3-000-personas-disfrutaron-en-el-festival-del-aire-2025-de-la-alcaldia\/ibague\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Cerca de 3.000 personas disfrutaron en el Festival del Aire 2025 de la Alcald\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/08\/3-2.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-bfc","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43226"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=43226"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43226\/revisions"}],"predecessor-version":[{"id":43228,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/43226\/revisions\/43228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/43227"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=43226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=43226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=43226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}