{"id":39219,"date":"2025-07-02T04:27:32","date_gmt":"2025-07-02T09:27:32","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=39219"},"modified":"2025-07-01T12:28:17","modified_gmt":"2025-07-01T17:28:17","slug":"desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/","title":{"rendered":"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres"},"content":{"rendered":"<h4><strong><em>En otro hecho de maltrato y agresi\u00f3n contra los animales ocurrido en C\u00facuta (Norte de Santander), fue imputada una persona que le habr\u00eda causado la muerte a un perro.<\/em><\/strong><\/h4>\n<p>La Fiscal\u00eda General de la Naci\u00f3n\u00a0present\u00f3 ante un juez de control de garant\u00edas a Darwin Hern\u00e1n Gonz\u00e1lez Dulcey, por\u00a0mantener en cautiverio y en precarias condiciones f\u00edsicas y de salud a 15 animales dom\u00e9sticos y silvestres\u00a0en una\u00a0finca del corregimiento La Dolores, en Palmira (Valle del Cauca).<\/p>\n<p>Por estos hechos, una\u00a0fiscal local\u00a0de la Seccional Valle del Cauca,\u00a0con el apoyo del Grupo Especial contra el Maltrato Animal (Gelma), imput\u00f3 a esta persona\u00a0los delitos de\u00a0aprovechamiento il\u00edcito de los recursos naturales renovables, muerte al animal y\u00a0lesiones que menoscaben gravemente la salud o la integridad f\u00edsica del animal,\u00a0estos dos \u00faltimos agravados. El procesado no acept\u00f3 los cargos y deber\u00e1 cumplir medida de aseguramiento privativa de la libertad en su lugar de residencia.<\/p>\n<p>El pasado 25 de junio, la Fiscal\u00eda,\u00a0la Polic\u00eda Nacional, la Corporaci\u00f3n Ambiental de Valle del Cauca (CVC) y otras entidades, se trasladaron al inmueble de\u00a0Gonz\u00e1lez Dulcey\u00a0y\u00a0encontraron a siete perros y gatos de diferentes razas, un guat\u00edn, dos guacamayas azules, dos loras amaz\u00f3nicas y tres tortugas morrocoy.<\/p>\n<p>Los animales presentaban deterioro en su salud. Adem\u00e1s, su conservaci\u00f3n y cuidado no eran adecuados. Esto les generaba atrofias musculares, estr\u00e9s y ansiedad.\u00a0Por su parte, los dom\u00e9sticos no ten\u00edan registro de haber sido vacunados, ni desparacitados.<\/p>\n<p>Muerte de un canino en C\u00facuta<\/p>\n<p>Una fiscal local de la Seccional Norte de Santander imput\u00f3 a Gabriel Malpica Guar\u00edn el delito de muerte a animal agravado.\u00a0Los hechos que se le atribuyen ocurrieron el pasado 12 de junio en una vivienda del barrio Do\u00f1a Nidia, en C\u00facuta (Norte de Santander), cuando at\u00f3 una cuerda al cuello de un perro criollo y lo levant\u00f3 hasta dejarlo inconsciente.<\/p>\n<p>El hombre habr\u00eda reaccionado violentamente porque el canino se le comi\u00f3 el almuerzo.<\/p>\n<p>Malpica Guar\u00edn no acept\u00f3 el cargo en su contra y, por disposici\u00f3n de un juez de control de garant\u00edas, deber\u00e1 cumplir medida de aseguramiento no privativa de la libertad.<\/p>\n<div class=\"td-gallery-slide-top\">\n<div class=\"td-gallery-title\"><\/div>\n<\/div>\n<div class=\"td-doubleSlider-1 \">\n<div class=\"td-slider\">\n<div class=\"td-slide-item td-item1\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 4 (1)\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"312\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-312x420.jpeg?resize=312%2C420&#038;ssl=1\" sizes=\"(max-width: 312px) 100vw, 312px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-312x420.jpeg 312w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-223x300.jpeg 223w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-762x1024.jpeg 762w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-768x1033.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1-696x936.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-4-1-1.jpeg 894w\" alt=\"fotografia de dos perros en una especie de corral, uno de raza putbull y el otro criollo\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item2\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 2 (1)\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"308\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-308x420.jpeg?resize=308%2C420&#038;ssl=1\" sizes=\"(max-width: 308px) 100vw, 308px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-308x420.jpeg 308w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-220x300.jpeg 220w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-752x1024.jpeg 752w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-768x1046.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2-696x948.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-2-1-2.jpeg 884w\" alt=\"fotografia de un perro al parecer de raza buldog en grave estado de desnutricion\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item3\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 5\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"311\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-311x420.jpeg?resize=311%2C420&#038;ssl=1\" sizes=\"(max-width: 311px) 100vw, 311px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-311x420.jpeg 311w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-222x300.jpeg 222w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-757x1024.jpeg 757w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-768x1038.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2-696x941.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-5-2.jpeg 892w\" alt=\"fotografia de dos perros, al parecer un de raza bulldog frances y otro de raza beagle, detras de una maya y en estado de desnutricion\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item4\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto1 (1)\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"339\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-339x420.jpeg?resize=339%2C420&#038;ssl=1\" sizes=\"(max-width: 339px) 100vw, 339px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-339x420.jpeg 339w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-242x300.jpeg 242w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-826x1024.jpeg 826w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-768x952.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-324x400.jpeg 324w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1-696x863.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto1-1-1.jpeg 976w\" alt=\"En la imagen se aprecia a varios gatos enjaulados y de color blanco.\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item5\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 6\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"304\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-304x420.jpeg?resize=304%2C420&#038;ssl=1\" sizes=\"(max-width: 304px) 100vw, 304px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-304x420.jpeg 304w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-217x300.jpeg 217w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-742x1024.jpeg 742w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-768x1059.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2-696x960.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-6-2.jpeg 880w\" alt=\"fotografia de tortuga icotea\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item6\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 7\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"302\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-302x420.jpeg?resize=302%2C420&#038;ssl=1\" sizes=\"(max-width: 302px) 100vw, 302px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-302x420.jpeg 302w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-216x300.jpeg 216w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-737x1024.jpeg 737w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-768x1067.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1-696x967.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-7-1.jpeg 872w\" alt=\"fotografia de un perro blanco\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item7\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 8\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"307\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-307x420.jpeg?resize=307%2C420&#038;ssl=1\" sizes=\"(max-width: 307px) 100vw, 307px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-307x420.jpeg 307w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-219x300.jpeg 219w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-749x1024.jpeg 749w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-768x1051.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1-696x952.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-8-1.jpeg 886w\" alt=\"fotografia de un perro criollo sobre una manta\" \/><\/a><\/figure>\n<\/div>\n<div class=\"td-slide-item td-item8\">\n<figure class=\"td-slide-galery-figure td-slide-popup-gallery\"><a class=\"slide-gallery-image-link\" title=\"foto 3 (1)\" href=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1.jpeg?ssl=1\" data-caption=\"\" data-description=\"\"><img data-recalc-dims=\"1\" height=\"420\" width=\"280\" decoding=\"async\" class=\"td-animation-stack-type0-2\" src=\"https:\/\/i0.wp.com\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-280x420.jpeg?resize=280%2C420&#038;ssl=1\" sizes=\"(max-width: 280px) 100vw, 280px\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-280x420.jpeg 280w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-200x300.jpeg 200w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-683x1024.jpeg 683w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-768x1152.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1-696x1044.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/foto-3-1-1.jpeg 804w\" alt=\"fotografia de tres perros en pesimas condiciones de salud\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En otro hecho de maltrato y agresi\u00f3n contra los animales ocurrido en C\u00facuta (Norte de Santander), fue imputada una persona que le habr\u00eda causado la muerte a un perro. La Fiscal\u00eda General de la Naci\u00f3n\u00a0present\u00f3 ante un juez de control de garant\u00edas a Darwin Hern\u00e1n Gonz\u00e1lez Dulcey, por\u00a0mantener en cautiverio<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":39220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[18],"tags":[],"class_list":["entry","author-diegoaguirre","post-39219","post","type-post","status-publish","format-standard","has-post-thumbnail","category-judicial"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"En otro hecho de maltrato y agresi\u00f3n contra los animales ocurrido en C\u00facuta (Norte de Santander), fue imputada una persona que le habr\u00eda causado la muerte a un perro. La Fiscal\u00eda General de la Naci\u00f3n\u00a0present\u00f3 ante un juez de control de garant\u00edas a Darwin Hern\u00e1n Gonz\u00e1lez Dulcey, por\u00a0mantener en cautiverioContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T09:27:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T17:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\",\"name\":\"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-07-02T09:27:32+00:00\",\"dateModified\":\"2025-07-01T17:28:17+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/","og_locale":"es_ES","og_type":"article","og_title":"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region","og_description":"En otro hecho de maltrato y agresi\u00f3n contra los animales ocurrido en C\u00facuta (Norte de Santander), fue imputada una persona que le habr\u00eda causado la muerte a un perro. La Fiscal\u00eda General de la Naci\u00f3n\u00a0present\u00f3 ante un juez de control de garant\u00edas a Darwin Hern\u00e1n Gonz\u00e1lez Dulcey, por\u00a0mantener en cautiverioContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/","og_site_name":"Ciudad y Region","article_published_time":"2025-07-02T09:27:32+00:00","article_modified_time":"2025-07-01T17:28:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/","name":"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1","datePublished":"2025-07-02T09:27:32+00:00","dateModified":"2025-07-01T17:28:17+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/desalmado-judicializado-hombre-que-mantenia-en-cautiverio-y-en-precarias-condiciones-a-15-animales-domesticos-y-silvestres\/judicial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Desalmado: Judicializado hombre que manten\u00eda en cautiverio y en precarias condiciones a 15 animales dom\u00e9sticos y silvestres"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/1-83.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-acz","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39219"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=39219"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39219\/revisions"}],"predecessor-version":[{"id":39221,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39219\/revisions\/39221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/39220"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=39219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=39219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=39219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}