{"id":39189,"date":"2025-07-01T08:28:52","date_gmt":"2025-07-01T13:28:52","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=39189"},"modified":"2025-07-01T08:28:52","modified_gmt":"2025-07-01T13:28:52","slug":"le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/","title":{"rendered":"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro"},"content":{"rendered":"<p>A trav\u00e9s de su cuenta de X el presidente Gustavo Petro le sali\u00f3 al paso a las cartas y la investigaci\u00f3n que public\u00f3 el diario El Pa\u00eds de Espa\u00f1a sobre el complot que se estar\u00eda fraguando desde Estados Unidos para derrocar a jefe de Estado colombiano.<\/p>\n<p>En su post el mandatario asegur\u00f3 que \u201che decidido responder cartas y unos hechos que aqu\u00ed muestra el periodista Espa\u00f1ol (Juan Diego) Quesada en el diario El Pa\u00eds\u00bb.<\/p>\n<p>En otro aparte record\u00f3 que \u201cle di el puesto de canciller a (\u00c1lvaro) Leyva, porque pens\u00e9 sin ning\u00fan c\u00e1lculo pol\u00edtico que se lo merec\u00eda al final de su vida\u00bb.<\/p>\n<p>Manifest\u00f3 adem\u00e1s que \u201cdurante meses he sido v\u00edctima de la injuria del se\u00f1or Leyva, y quise simplemente responder a lo que consideraba un acto de venganza b\u00e1rbaro, canalla, de alguien que simplemente hab\u00eda ayudado de coraz\u00f3n\u00bb.<\/p>\n<blockquote><p>\u201cCon el correr del tiempo no quise aceptar pasos oscuros en la canciller\u00eda, como el caso de Thomas y Gregg, por lo cual lo sancion\u00f3, la procuradur\u00eda; tampoco quise que su hijo, ocupase la canciller\u00eda o una embajada, como si la democracia fuera hereditaria. El nombramiento de Laura Sarabia y (Armando) Benedetti lo llen\u00f3 de odio. Debo decir que jam\u00e1s, hasta hace poco tiempo, me enter\u00e9 de esa petici\u00f3n que hizo a Benedetti y era dirigida a m\u00ed\u00bb, coment\u00f3.<\/p><\/blockquote>\n<p>Dijo adem\u00e1s que \u201cel caso Leyva me hace pensar que la conducta de lo que llamo oligarqu\u00eda, a la que indudablemente pertenece Leyva, es la doble moral, piensa el estado como hereditario, con derecho a negocios con el erario; es incapaz de establecer relaciones basadas en el respeto a la otra persona y a los argumentos, es una ingenuidad pensar que lo har\u00eda\u00bb.<\/p>\n<blockquote><p>\u201cEl acuerdo nacional se vuelve fantasmagor\u00eda y discurso. Traicionan, aunque siempre hay que insistir en el acuerdo y la paz\u00bb, anot\u00f3.<\/p><\/blockquote>\n<p>En su post el presidente Petro dijo que \u201cpens\u00e9 enga\u00f1ado, que ten\u00eda una genuina vocaci\u00f3n de paz\u00bb, por parte de Leyva.<\/p>\n<p>Sin embargo, \u201cLeyva en realidad no ayud\u00f3 al proceso de paz del M19, pero se comprometi\u00f3 durante d\u00e9cadas al proceso con las farc. Pens\u00e9 que hab\u00eda sido perseguido por ello; hoy conoci\u00e9ndolo personalmente, creo que tambien buscaba otras cosas con la paz, menos santas\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de su cuenta de X el presidente Gustavo Petro le sali\u00f3 al paso a las cartas y la investigaci\u00f3n que public\u00f3 el diario El Pa\u00eds de Espa\u00f1a sobre el complot que se estar\u00eda fraguando desde Estados Unidos para derrocar a jefe de Estado colombiano. En su post el<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":39190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["entry","author-diegoaguirre","post-39189","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"A trav\u00e9s de su cuenta de X el presidente Gustavo Petro le sali\u00f3 al paso a las cartas y la investigaci\u00f3n que public\u00f3 el diario El Pa\u00eds de Espa\u00f1a sobre el complot que se estar\u00eda fraguando desde Estados Unidos para derrocar a jefe de Estado colombiano. En su post elContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-01T13:28:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\",\"name\":\"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-07-01T13:28:52+00:00\",\"dateModified\":\"2025-07-01T13:28:52+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/","og_locale":"es_ES","og_type":"article","og_title":"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region","og_description":"A trav\u00e9s de su cuenta de X el presidente Gustavo Petro le sali\u00f3 al paso a las cartas y la investigaci\u00f3n que public\u00f3 el diario El Pa\u00eds de Espa\u00f1a sobre el complot que se estar\u00eda fraguando desde Estados Unidos para derrocar a jefe de Estado colombiano. En su post elContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/","og_site_name":"Ciudad y Region","article_published_time":"2025-07-01T13:28:52+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/","name":"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1","datePublished":"2025-07-01T13:28:52+00:00","dateModified":"2025-07-01T13:28:52+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/le-di-el-puesto-de-canciller-a-leyva-porque-pense-que-se-lo-merecia-al-final-de-su-vida-presidente-petro\/politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"\u2018Le di el puesto de Canciller a Leyva porque pens\u00e9 que se lo merec\u00eda al final de su vida\u2019: presidente Petro"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/07\/3-92.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-ac5","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39189"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=39189"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39189\/revisions"}],"predecessor-version":[{"id":39191,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39189\/revisions\/39191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/39190"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=39189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=39189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=39189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}