{"id":39102,"date":"2025-06-28T04:53:58","date_gmt":"2025-06-28T09:53:58","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=39102"},"modified":"2025-06-27T18:54:40","modified_gmt":"2025-06-27T23:54:40","slug":"arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/","title":{"rendered":"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos"},"content":{"rendered":"<p>Un plan de seguridad para brindar tranquilidad y bienestar a los turistas que se movilizar\u00e1n por zonas costeras y fluviales a lo largo y ancho del territorio nacional durante este puente festivo, en el marco de la temporada vacacional de mitad de a\u00f1o, puso en marcha el Gobierno en todo el pa\u00eds con apoyo de la Armada Nacional.<\/p>\n<p>Mediante esta estrategia, denominada Plan Acorazado, la fuerza naval despleg\u00f3 toda la capacidad de sus unidades de guardacostas, aviaci\u00f3n naval, flotillas de superficie, brigadas y batallones de la Infanter\u00eda de Marina que cumplen operaciones de control y vigilancia mar\u00edtima y fluvial, adem\u00e1s de patrullajes en \u00e1reas costeras y terrestres de su responsabilidad.<\/p>\n<p>Las unidades de Guardacostas supervisan las condiciones de seguridad en embarcaciones tur\u00edsticas, verificando el uso obligatorio del chaleco salvavidas, el cumplimiento de las normas mar\u00edtimas y la no conducci\u00f3n de naves bajo efectos de alcohol o sustancias psicoactivas.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/i0.wp.com\/www.presidencia.gov.co\/prensa\/galFotosNotas\/250627-Arranca-Plan-Acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios-2-1280.jpg?w=1440&#038;ssl=1\" alt=\"\" \/><\/p>\n<h2>En el Ca\u200bribe<\/h2>\n<p>\u200bLa Fuerza Naval del Caribe despleg\u00f3 m\u00e1s de 6.000 hombres y mujeres en un dispositivo que contempla operaciones en zonas insulares, as\u00ed como vigilancia en parques naturales, playas, ejes viales y corredores fluviales de los departamentos de Bol\u00edvar, C\u00f3rdoba, Sucre, Magdalena, y el Archipi\u00e9lago de San Andr\u00e9s, Providencia y Santa Catalina.<\/p>\n<p>Se mantiene adem\u00e1s una presencia activa en los r\u00edos Atrato, Cauca y Magdalena, puntos clave para el tr\u00e1nsito de pasajeros y mercanc\u00edas.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/i0.wp.com\/www.presidencia.gov.co\/prensa\/galFotosNotas\/250627-Arranca-Plan-Acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios-3-1280.jpg?w=1440&#038;ssl=1\" alt=\"\" \/><\/p>\n<h2>En el \u200b\u200bPac\u00edfico<\/h2>\n<p>\u200bCon el prop\u00f3sito de fortalecer la presencia institucional en la regi\u00f3n, se han implementado estrategias de seguridad en Cauca, Choc\u00f3, Nari\u00f1o y Valle del Cauca, llevando a cabo controles en los cinco parques nacionales naturales de la zona: Gorgona, Malpelo, Sanquianga, Uramba y Utr\u00eda.<\/p>\n<p>M\u00e1s de 2.000 tripulantes de la Fuerza Naval del Pac\u00edfico se ha desplegado en distintas zonas estrat\u00e9gicas, tanto en mares como en r\u00edos, tierra y aire, para salvaguardar a la comunidad y proteger los corredores de movilidad.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/i0.wp.com\/www.presidencia.gov.co\/prensa\/galFotosNotas\/250627-Arranca-Plan-Acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios-4-1280.jpg?w=1440&#038;ssl=1\" alt=\"\" \/><\/p>\n<h2>En la \u200bAmazon\u00eda<\/h2>\n<p>\u200bDe manera conjunta con el Ej\u00e9rcito Nacional y la Fuerza Aeroespacial Colombiana, con el acompa\u00f1amiento de autoridades regionales y locales, la Fuerza Naval de la Amazon\u00eda adelanta operaciones fluviales para reforzar la seguridad en el sur del pa\u00eds, haciendo acompa\u00f1amiento e inspecci\u00f3n a tripulaciones y usuarios de todo tipo de embarcaciones en muelles y r\u00edos.<\/p>\n<p>Se adelantan jornadas pedag\u00f3gicas de sensibilizaci\u00f3n, dirigidas tanto a habitantes de zonas ribere\u00f1as como a turistas nacionales y extranjeros que eligen la regi\u00f3n amaz\u00f3nica como destino por su riqueza natural, cultural y biodiversidad.<\/p>\n<p>Se mantiene una presencia constante en la frontera amaz\u00f3nica, velando por un entorno seguro y propicio para el desarrollo del turismo ecol\u00f3gico en esta zona estrat\u00e9gica del pa\u00eds, as\u00ed como un despliegue operativo en Mapirip\u00e1n (Meta), con el objetivo de preservar el orden, proteger los derechos de los ciudadanos y brindar apoyo integral a las poblaciones vulnerables durante esta temporada tur\u00edstica.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/i0.wp.com\/www.presidencia.gov.co\/prensa\/galFotosNotas\/250627-Arranca-Plan-Acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios-5-1280.jpg?w=1440&#038;ssl=1\" alt=\"\" \/><\/p>\n<h2>En la Ori\u200bnoqu\u00eda<\/h2>\n<p>\u200bEn Arauca, Casanare, Guain\u00eda, Meta y Vichada, la Fuerza Naval de la Orinoqu\u00eda despleg\u00f3 unidades y capacidades diferenciales como deslizadores (hovercrafts), elementos de operaciones fluviales, patrulleras de apoyo fluvial, patrullas log\u00edsticas de combate y unidades de reacci\u00f3n r\u00e1pida de guardacostas, protegiendo los principales r\u00edos como el Orinoco, Meta, Arauca, Guain\u00eda y Guaviare.<\/p>\n<p>Mediante el plan &#8216;Viaje Seguro &#8211; Orinoqu\u00eda Segura&#8217;, integra m\u00e1s de 1.900 hombres y mujeres de la Armada en la regi\u00f3n, fortaleciendo as\u00ed la relaci\u00f3n con la poblaci\u00f3n local mediante canales de comunicaci\u00f3n efectivos.<\/p>\n<p>Este esfuerzo est\u00e1 articulado con las Fuerzas Militares, la Polic\u00eda Nacional y entidades gubernamentales y tiene como objetivo consolidar la presencia del Estado y mantener el orden p\u00fablico en esta importante regi\u00f3n del pa\u00eds.<\/p>\n<p>El Gobierno hace un llamado a propios y turistas para seguir las recomendaciones de las autoridades en esta temporada vacacional de mitad de a\u00f1o, especialmente las del personal de Guardacostas y la Direcci\u00f3n General Mar\u00edtima.<\/p>\n<p>Es clave utilizar los muelles autorizados para los zarpes, portar los equipos de seguridad durante sus recorridos a bordo de embarcaciones, evitar conductas de riesgo durante actividades acu\u00e1ticas y cumplir con la normatividad vigente a fin de prevenir incidentes y garantizar una navegaci\u00f3n segura y responsable.<\/p>\n<p>Asimismo, invita a la ciudadan\u00eda a reportar cualquier situaci\u00f3n sospechosa a las l\u00edneas 123, 146, 147, o mediante el canal VHF Marino de cada regi\u00f3n.<\/p>\n<p>De manera adicional, los Gaulas militares en cada municipio contin\u00faan promoviendo la denuncia ciudadana frente a delitos como el secuestro y la extorsi\u00f3n, mediante la l\u00ednea gratuita 147 y la campa\u00f1a &#8216;Yo no pago, yo denuncio&#8217;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un plan de seguridad para brindar tranquilidad y bienestar a los turistas que se movilizar\u00e1n por zonas costeras y fluviales a lo largo y ancho del territorio nacional durante este puente festivo, en el marco de la temporada vacacional de mitad de a\u00f1o, puso en marcha el Gobierno en todo<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":39103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[23],"tags":[],"class_list":["entry","author-diegoaguirre","post-39102","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"Un plan de seguridad para brindar tranquilidad y bienestar a los turistas que se movilizar\u00e1n por zonas costeras y fluviales a lo largo y ancho del territorio nacional durante este puente festivo, en el marco de la temporada vacacional de mitad de a\u00f1o, puso en marcha el Gobierno en todoContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-28T09:53:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T23:54:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\",\"name\":\"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-06-28T09:53:58+00:00\",\"dateModified\":\"2025-06-27T23:54:40+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region","og_description":"Un plan de seguridad para brindar tranquilidad y bienestar a los turistas que se movilizar\u00e1n por zonas costeras y fluviales a lo largo y ancho del territorio nacional durante este puente festivo, en el marco de la temporada vacacional de mitad de a\u00f1o, puso en marcha el Gobierno en todoContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/","og_site_name":"Ciudad y Region","article_published_time":"2025-06-28T09:53:58+00:00","article_modified_time":"2025-06-27T23:54:40+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/","name":"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1","datePublished":"2025-06-28T09:53:58+00:00","dateModified":"2025-06-27T23:54:40+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/arranca-plan-acorazado-estrategia-para-brindar-seguridad-a-turistas-en-mares-y-rios\/nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Arranca Plan Acorazado: estrategia para brindar seguridad a turistas en mares y r\u00edos"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/2-57.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-aaG","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39102"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=39102"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39102\/revisions"}],"predecessor-version":[{"id":39104,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/39102\/revisions\/39104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/39103"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=39102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=39102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=39102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}