{"id":38867,"date":"2025-06-26T04:50:29","date_gmt":"2025-06-26T09:50:29","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=38867"},"modified":"2025-06-25T12:51:01","modified_gmt":"2025-06-25T17:51:01","slug":"gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/","title":{"rendered":"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas"},"content":{"rendered":"<div>La Unidad de Planificaci\u00f3n Rural Agropecuaria (UPRA) report\u00f3 que en mayo de 2025 ingresaron 654.252 toneladas de alimentos a las principales centrales mayoristas del pa\u00eds, el volumen m\u00e1s alto desde enero de 2013, cuando se comenz\u00f3 a hacer esta medici\u00f3n de forma sistem\u00e1tica.<\/div>\n<div><\/div>\n<div>El aumento fue del 6,8 % respecto al mismo mes de 2024, consolidando una tendencia de crecimiento en la oferta y disponibilidad de alimentos frescos y procesados en las ciudades del pa\u00eds.<\/div>\n<div><\/div>\n<div>Este comportamiento positivo se reflej\u00f3 en 16 de las 23 ciudades que tienen mercados mayoristas, con aumentos especialmente en Tibasosa (67,8 %), Manizales (29,2 %), Villavicencio (15,3 %), Armenia (12,5 %), Medell\u00edn (11,3 %) y Bogot\u00e1 (8,4 %).<\/div>\n<div><\/div>\n<div>No obstante, se presentaron reducciones en puntos como Ipiales (-25,4 %) y Santa Marta (-22,8 %).<\/div>\n<div><\/div>\n<div>Por grupos de alimentos el mayor dinamismo se dio en productos procesados (15,3 %), granos y cereales (12,8 %), pescados (10,2 %), l\u00e1cteos y huevos (9,2 %) y tub\u00e9rculos, ra\u00edces y pl\u00e1tanos (7,0 %).<\/div>\n<div><\/div>\n<div>Tambi\u00e9n aumentaron las frutas (5,9 %) y las verduras y hortalizas (4,4 %). \u00danicamente el grupo de carnes present\u00f3 una ligera disminuci\u00f3n (-1,7 %).<\/div>\n<div><\/div>\n<blockquote>\n<div>\u201cEstos datos confirman que el campo est\u00e1 respondiendo a la demanda alimentaria del pa\u00eds. Para planificar con eficiencia necesitamos saber qu\u00e9 llega, desde d\u00f3nde y en qu\u00e9 cantidades. El monitoreo t\u00e9cnico del abastecimiento es clave para garantizar la seguridad alimentaria y orientar la producci\u00f3n desde los territorios rurales\u00bb, afirm\u00f3 Dora In\u00e9s Rey, directora de la UPRA.<\/div>\n<\/blockquote>\n<div><\/div>\n<h2>Buen registro en verduras y hortalizas<\/h2>\n<div><\/div>\n<div>En el grupo de verduras y hortalizas ingresaron 180.620 toneladas, con comportamientos destacados en el abastecimiento de fr\u00edjol (33,9 %), ma\u00edz (32 %), apio (19,4 %), ajo (18,8 %), pepino cohombro (17 %) y piment\u00f3n (16,2 %).<\/div>\n<div><\/div>\n<div>Tambi\u00e9n se reportaron aumentos en zanahoria, cebolla cabezona, habichuela y otras hortalizas. Por el contrario, disminuy\u00f3 el ingreso de arveja verde, repollo, tomate, cebolla junca, ahuyama y lechuga.<\/div>\n<div><\/div>\n<div>En Cali, una de las principales ciudades receptoras, el 42 % del volumen de verduras y hortalizas provino del Valle del Cauca, seguido por Nari\u00f1o (22,8 %), Bogot\u00e1 (16,3 %), Boyac\u00e1 (14,3 %) y Cauca (2 %), evidenciando la articulaci\u00f3n entre regiones productoras y mercados urbanos.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Unidad de Planificaci\u00f3n Rural Agropecuaria (UPRA) report\u00f3 que en mayo de 2025 ingresaron 654.252 toneladas de alimentos a las principales centrales mayoristas del pa\u00eds, el volumen m\u00e1s alto desde enero de 2013, cuando se comenz\u00f3 a hacer esta medici\u00f3n de forma sistem\u00e1tica. El aumento fue del 6,8 % respecto<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":38868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["entry","author-diegoaguirre","post-38867","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"La Unidad de Planificaci\u00f3n Rural Agropecuaria (UPRA) report\u00f3 que en mayo de 2025 ingresaron 654.252 toneladas de alimentos a las principales centrales mayoristas del pa\u00eds, el volumen m\u00e1s alto desde enero de 2013, cuando se comenz\u00f3 a hacer esta medici\u00f3n de forma sistem\u00e1tica. El aumento fue del 6,8 % respectoContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T09:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T17:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\",\"name\":\"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-06-26T09:50:29+00:00\",\"dateModified\":\"2025-06-25T17:51:01+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region","og_description":"La Unidad de Planificaci\u00f3n Rural Agropecuaria (UPRA) report\u00f3 que en mayo de 2025 ingresaron 654.252 toneladas de alimentos a las principales centrales mayoristas del pa\u00eds, el volumen m\u00e1s alto desde enero de 2013, cuando se comenz\u00f3 a hacer esta medici\u00f3n de forma sistem\u00e1tica. El aumento fue del 6,8 % respectoContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/","og_site_name":"Ciudad y Region","article_published_time":"2025-06-26T09:50:29+00:00","article_modified_time":"2025-06-25T17:51:01+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/","name":"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1","datePublished":"2025-06-26T09:50:29+00:00","dateModified":"2025-06-25T17:51:01+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/gobierno-afirma-que-en-mayo-hubo-el-mas-alto-ingreso-de-alimentos-a-las-centrales-mayoristas-de-los-ultimos-12-anos-654-252-toneladas\/economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Gobierno afirma que en mayo hubo el m\u00e1s alto ingreso de alimentos a las centrales mayoristas de los \u00faltimos 12 a\u00f1os: 654.252 toneladas"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/mercado-plaza.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-a6T","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38867"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=38867"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38867\/revisions"}],"predecessor-version":[{"id":38869,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38867\/revisions\/38869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/38868"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=38867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=38867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=38867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}