{"id":38319,"date":"2025-06-19T04:59:33","date_gmt":"2025-06-19T09:59:33","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=38319"},"modified":"2025-06-18T16:01:24","modified_gmt":"2025-06-18T21:01:24","slug":"cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/","title":{"rendered":"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a"},"content":{"rendered":"<p>En la m\u00e1s reciente emisi\u00f3n de El Puente, espacio creado por el Ministerio de Relaciones Exteriores para acercar a la ciudadan\u00eda a los temas clave de la agenda internacional, el Gobierno nacional insisti\u00f3 en la necesidad de replantear la forma en que la comunidad internacional clasifica la hoja de coca.<\/p>\n<p>Tambi\u00e9n se presentaron los principales efectos que tendr\u00e1 la nueva pol\u00edtica migratoria de Espa\u00f1a sobre la poblaci\u00f3n colombiana residente en ese pa\u00eds.<\/p>\n<p>La transmisi\u00f3n se llev\u00f3 a cabo este martes a las 7:00 a.\u202fm. a trav\u00e9s de las plataformas digitales de la Canciller\u00eda.<\/p>\n<p>Durante el espacio, el Gobierno del Cambio reiter\u00f3 su postura frente a la actual clasificaci\u00f3n de la hoja de coca en la Lista I de la Convenci\u00f3n \u00danica sobre Estupefacientes de 1961, donde figura junto a sustancias consideradas altamente peligrosas.<\/p>\n<p>Seg\u00fan explic\u00f3 la Canciller\u00eda, esta inclusi\u00f3n se basa en un informe carente de rigor cient\u00edfico elaborado en los a\u00f1os cincuenta, lo que ha favorecido una visi\u00f3n estigmatizante que ignora el valor tradicional, cultural y terap\u00e9utico de la planta, as\u00ed como su potencial para generar alternativas de desarrollo sostenible en los territorios.<\/p>\n<p>En ese contexto, Colombia y Bolivia presentaron una solicitud conjunta a la Organizaci\u00f3n Mundial de la Salud (OMS) para que se inicie un proceso formal de revisi\u00f3n.<\/p>\n<p>Esta iniciativa deber\u00e1 pasar primero por el Comit\u00e9 de Expertos en Farmacodependencia de la OMS, antes de llegar a la Comisi\u00f3n de Estupefacientes, que ser\u00e1 la encargada de tomar una decisi\u00f3n final.<\/p>\n<p>El objetivo: que la regulaci\u00f3n internacional se base en evidencia cient\u00edfica, principios de salud p\u00fablica y derechos humanos, y no en prejuicios hist\u00f3ricos ni intereses geopol\u00edticos.\u200b<\/p>\n<p>Adem\u00e1s, se compartieron datos que respaldan el uso tradicional de la planta. La hoja de coca contiene nutrientes como vitaminas A, B1, B2 y C, as\u00ed como minerales como hierro, calcio y f\u00f3sforo.<\/p>\n<p>En su estado natural no genera adicci\u00f3n, y estudios toxicol\u00f3gicos han demostrado que su consumo tradicional, como en infusiones o mambeo, no representa riesgos significativos para la salud.<\/p>\n<p>Con estos argumentos, el Gobierno impulsa una estrategia internacional que permita aprovechar legalmente la hoja de coca en sectores como el agr\u00edcola, medicinal, cosm\u00e9tico y agroindustrial.<\/p>\n<p>Este enfoque busca no solo romper con el paradigma prohibicionista, sino tambi\u00e9n aportar a la paz en regiones golpeadas por el narcotr\u00e1fico, reconociendo la hoja como un s\u00edmbolo de identidad para comunidades ind\u00edgenas, afrodescendientes y campesinas.<\/p>\n<p>En la segunda parte del encuentro, se analiz\u00f3 la evoluci\u00f3n de la pol\u00edtica migratoria de Espa\u00f1a.<\/p>\n<p>La Canciller\u00eda explic\u00f3 que se mantiene atenta a los efectos que estos cambios puedan tener sobre los colombianos que viven en ese pa\u00eds y reiter\u00f3 su compromiso de seguir fortaleciendo la atenci\u00f3n consular, mediante canales de cooperaci\u00f3n bilateral que garanticen la dignidad, la integraci\u00f3n y el acceso a nuevas oportunidades para la di\u00e1spora.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la m\u00e1s reciente emisi\u00f3n de El Puente, espacio creado por el Ministerio de Relaciones Exteriores para acercar a la ciudadan\u00eda a los temas clave de la agenda internacional, el Gobierno nacional insisti\u00f3 en la necesidad de replantear la forma en que la comunidad internacional clasifica la hoja de coca.<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":38320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[23],"tags":[],"class_list":["entry","author-diegoaguirre","post-38319","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"En la m\u00e1s reciente emisi\u00f3n de El Puente, espacio creado por el Ministerio de Relaciones Exteriores para acercar a la ciudadan\u00eda a los temas clave de la agenda internacional, el Gobierno nacional insisti\u00f3 en la necesidad de replantear la forma en que la comunidad internacional clasifica la hoja de coca.Continuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-19T09:59:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T21:01:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\",\"name\":\"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-06-19T09:59:33+00:00\",\"dateModified\":\"2025-06-18T21:01:24+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region","og_description":"En la m\u00e1s reciente emisi\u00f3n de El Puente, espacio creado por el Ministerio de Relaciones Exteriores para acercar a la ciudadan\u00eda a los temas clave de la agenda internacional, el Gobierno nacional insisti\u00f3 en la necesidad de replantear la forma en que la comunidad internacional clasifica la hoja de coca.Continuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/","og_site_name":"Ciudad y Region","article_published_time":"2025-06-19T09:59:33+00:00","article_modified_time":"2025-06-18T21:01:24+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/","name":"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1","datePublished":"2025-06-19T09:59:33+00:00","dateModified":"2025-06-18T21:01:24+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/cancilleria-aborda-usos-licitos-de-la-hoja-de-coca-y-politica-migratoria-de-espana\/nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Canciller\u00eda aborda usos l\u00edcitos de la hoja de coca y pol\u00edtica migratoria de Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-31.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-9Y3","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38319"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=38319"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38319\/revisions"}],"predecessor-version":[{"id":38321,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/38319\/revisions\/38321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/38320"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=38319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=38319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=38319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}