{"id":37260,"date":"2025-06-07T04:26:58","date_gmt":"2025-06-07T09:26:58","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=37260"},"modified":"2025-06-06T19:28:39","modified_gmt":"2025-06-07T00:28:39","slug":"victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/","title":{"rendered":"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia"},"content":{"rendered":"<p>Lo hicieron en el II Plenario Nacional de la Mesa de Participaci\u00f3n Efectiva donde se trataron temas de salud mental y acceso a tierras, entre otros.<\/p>\n<p>Durante tres d\u00edas, la capital tolimense fue el punto de encuentro para las voces de cientos de v\u00edctimas del conflicto armado en el marco del II Plenario Nacional de la Mesa de Participaci\u00f3n Efectiva.<\/p>\n<p>Con el respaldo de la Gobernaci\u00f3n del Tolima, las organizaciones de v\u00edctimas lideraron espacios de di\u00e1logo, an\u00e1lisis y propuestas orientadas a su reparaci\u00f3n integral y al fortalecimiento de su papel en la construcci\u00f3n de paz.<\/p>\n<p>Temas como salud mental, acceso a tierras y participaci\u00f3n efectiva fueron abordados en mesas de trabajo donde las v\u00edctimas no solo fueron escuchadas, sino que tambi\u00e9n propusieron soluciones concretas. Todo esto en el marco de la implementaci\u00f3n de la Ley 1448 de 2011 y su reciente actualizaci\u00f3n con la Ley 2421 de 2024.<\/p>\n<p>De acuerdo con Lina Sandoval: \u201cesta iniciativa es se\u00f1al de compromiso pionero, mostrando efectividad real en el cumplimiento por la paz y la seguridad en el departamento\u201d.<\/p>\n<p>Un espacio clave fue la divulgaci\u00f3n de la estrategia nacional \u201cVoces de las V\u00edctimas: Llamado por la vida y la paz\u201d, impulsada por organizaciones sociales y respaldada por entidades estatales. Esta estrategia busca no solo visibilizar los derechos de las v\u00edctimas, sino tambi\u00e9n fortalecer su liderazgo en procesos de reconciliaci\u00f3n y construcci\u00f3n de pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo hicieron en el II Plenario Nacional de la Mesa de Participaci\u00f3n Efectiva donde se trataron temas de salud mental y acceso a tierras, entre otros. Durante tres d\u00edas, la capital tolimense fue el punto de encuentro para las voces de cientos de v\u00edctimas del conflicto armado en el marco<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":37261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13],"tags":[],"class_list":["entry","author-diegoaguirre","post-37260","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regional"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"Lo hicieron en el II Plenario Nacional de la Mesa de Participaci\u00f3n Efectiva donde se trataron temas de salud mental y acceso a tierras, entre otros. Durante tres d\u00edas, la capital tolimense fue el punto de encuentro para las voces de cientos de v\u00edctimas del conflicto armado en el marcoContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-07T09:26:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-07T00:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\",\"name\":\"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-06-07T09:26:58+00:00\",\"dateModified\":\"2025-06-07T00:28:39+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/","og_locale":"es_ES","og_type":"article","og_title":"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region","og_description":"Lo hicieron en el II Plenario Nacional de la Mesa de Participaci\u00f3n Efectiva donde se trataron temas de salud mental y acceso a tierras, entre otros. Durante tres d\u00edas, la capital tolimense fue el punto de encuentro para las voces de cientos de v\u00edctimas del conflicto armado en el marcoContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/","og_site_name":"Ciudad y Region","article_published_time":"2025-06-07T09:26:58+00:00","article_modified_time":"2025-06-07T00:28:39+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/","name":"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1","datePublished":"2025-06-07T09:26:58+00:00","dateModified":"2025-06-07T00:28:39+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/victimas-del-conflicto-armado-de-todo-el-pais-se-dieron-cita-en-ibague-para-construir-propuestas-de-paz-desde-su-experiencia\/regional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"V\u00edctimas del conflicto armado de todo el pa\u00eds se dieron cita en Ibagu\u00e9 para construir propuestas de paz desde su experiencia"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/06\/1-18.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-9GY","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/37260"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=37260"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/37260\/revisions"}],"predecessor-version":[{"id":37262,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/37260\/revisions\/37262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/37261"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=37260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=37260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=37260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}