{"id":35660,"date":"2025-05-16T07:50:07","date_gmt":"2025-05-16T12:50:07","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=35660"},"modified":"2025-05-16T07:50:07","modified_gmt":"2025-05-16T12:50:07","slug":"colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/","title":{"rendered":"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS"},"content":{"rendered":"<p>El presidente Gustavo Petro anunci\u00f3 este viernes desde China que Colombia radic\u00f3 formalmente la solicitud de ingreso al Nuevo Banco de Desarrollo (NDB, por sus siglas en ingl\u00e9s) de los BRICS\u200b.<\/p>\n<p>La noticia la dio el mandatario\u200b\u00a0en Shangh\u00e1i, en el marco de su visita oficial por el gigante asi\u00e1tico, al t\u00e9rmino de una reuni\u00f3n con Dilma Rousseff, actual presidenta de este banco multilateral de desarrollo, creado por Brasil, Rusia, India, China y Sudafrica (BRICS, acr\u00f3nimo para referirse a este bloque de pa\u00edses) en 2015.<\/p>\n<p>Una carta firmada por el ministro de Hacienda y Cr\u00e9dito P\u00fablico, Germ\u00e1n \u00c1vila Plazas, expresa el inter\u00e9s de Colombia de hacer parte del NBD, como miembro prestatario.<\/p>\n<p>Es decir, un pa\u00eds que forma parte del Nuevo Banco de Desarrollo y recibe pr\u00e9stamos a tasas bajas de ese banco para financiar proyectos de desarrollo en infraestructura, energ\u00edas renovables, salud, entre otros.<\/p>\n<p>En ese sentido, el ministro inform\u00f3 a Rousseff que Colombia \u201cest\u00e1 dispuesta a suscribir 5.125 acciones del capital autorizado del Nuevo Banco de Desarrollo, de las cuales 4.100 corresponden a acciones exigibles (como garant\u00eda) y 1.025 corresponden a acciones pagadas (en efectivo)\u201d.<\/p>\n<blockquote><p>\n\u201cEsto equivale a un capital suscrito (monto total comprometido a aportar) de USD 512,5 millones (2,1 billones de pesos), que incluye un capital exigible de USD 410 millones (1,7 billones de pesos) y un capital pagado de USD 102,5 millones (429 mil millones de pesos)\u201d, dice la carta.<\/p><\/blockquote>\n<p>El primer pago, indica el ministro en la carta de solicitud de ingreso, se realizar\u00e1 dentro de los seis meses siguientes a la fecha en que Colombia entregue el documento de adhesi\u00f3n al convenio al Gobierno de Brasil.<\/p>\n<p>La solicitud de Colombia para unirse al Nuevo Banco de Desarrollo (NDB) marca un paso estrat\u00e9gico hacia la diversificaci\u00f3n de las fuentes de financiamiento internacional y la consolidaci\u00f3n de alianzas con econom\u00edas emergentes.<\/p>\n<p>El NDB representar\u00e1 para el pa\u00eds una alternativa concreta a las instituciones financieras tradicionales como el Fondo Monetario Internacional (FMI) o el Banco Mundial.<\/p>\n<p>La adhesi\u00f3n a esta entidad le permitir\u00eda a Colombia acceder a cr\u00e9ditos con condiciones favorables y fortalecer su capacidad de respuesta frente a desaf\u00edos como el cambio clim\u00e1tico o las crisis econ\u00f3micas globales.<\/p>\n<p>Adem\u00e1s, esto posiciona al pa\u00eds como un actor relevante dentro de una arquitectura financiera donde las econom\u00edas del sur global buscan mayor autonom\u00eda y equidad en la toma de decisiones.<\/p>\n<p>Al comprometerse con un capital suscrito de m\u00e1s de 500 millones de d\u00f3lares, Colombia no solo demuestra confianza en la gobernanza del NDB, sino que se proyecta como un socio comprometido con el fortalecimiento de la cooperaci\u00f3n Sur-Sur<\/p>\n<p>Esta participaci\u00f3n tambi\u00e9n abre nuevas puertas para el sector privado colombiano y proyectos p\u00fablicos que requieren financiaci\u00f3n innovadora y sostenible.<\/p>\n<p>Dilma Rousseff, presidenta del NDB y expresidenta de Brasil, asegur\u00f3 en su intervenci\u00f3n en el Foro de China-Celac, en el particip\u00f3 el presidente Gustavo Petro, que \u201cel unilateralismo representa un retroceso. Substituye el derecho por la fuerza y la cooperaci\u00f3n por la imposici\u00f3n\u201d.<\/p>\n<p>Afirm\u00f3 que el Banco de los BRICS\u200b \u201cfue concebido para apoyar el desarrollo en el sur global, sin vetos, sin condicionalidades y con respecto a la soberan\u00eda nacional de cada pa\u00eds. Somos el primer banco multilateral totalmente establecido por y para el pa\u00eds en desarrollo y mercados emergentes\u201d.<\/p>\n<blockquote><p>\n\u201cHasta el momento, hemos aprobado 122 proyectos de inversi\u00f3n, totalizando cerca de 40 billones de d\u00f3lares. El uso de monedas locales se convirti\u00f3 en una pol\u00edtica diferenciada. Actualmente, cerca del 24% de nuestras operaciones de inversi\u00f3n y 31% de nuestras captaciones son realizadas en monedas locales\u201d, dijo.<\/p><\/blockquote>\n<p>En ese sentido, la entrada de Colombia al NDB puede convertirse en una plataforma para estrechar lazos estrat\u00e9gicos con pa\u00edses como Brasil, India, China y Sud\u00e1frica, lo cual puede traducirse en mayor comercio, inversi\u00f3n extranjera directa y transferencia de tecnolog\u00eda.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Gustavo Petro anunci\u00f3 este viernes desde China que Colombia radic\u00f3 formalmente la solicitud de ingreso al Nuevo Banco de Desarrollo (NDB, por sus siglas en ingl\u00e9s) de los BRICS\u200b. La noticia la dio el mandatario\u200b\u00a0en Shangh\u00e1i, en el marco de su visita oficial por el gigante asi\u00e1tico, al<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":35661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["entry","author-diegoaguirre","post-35660","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"El presidente Gustavo Petro anunci\u00f3 este viernes desde China que Colombia radic\u00f3 formalmente la solicitud de ingreso al Nuevo Banco de Desarrollo (NDB, por sus siglas en ingl\u00e9s) de los BRICS\u200b. La noticia la dio el mandatario\u200b\u00a0en Shangh\u00e1i, en el marco de su visita oficial por el gigante asi\u00e1tico, alContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-16T12:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\",\"name\":\"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-05-16T12:50:07+00:00\",\"dateModified\":\"2025-05-16T12:50:07+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region","og_description":"El presidente Gustavo Petro anunci\u00f3 este viernes desde China que Colombia radic\u00f3 formalmente la solicitud de ingreso al Nuevo Banco de Desarrollo (NDB, por sus siglas en ingl\u00e9s) de los BRICS\u200b. La noticia la dio el mandatario\u200b\u00a0en Shangh\u00e1i, en el marco de su visita oficial por el gigante asi\u00e1tico, alContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/","og_site_name":"Ciudad y Region","article_published_time":"2025-05-16T12:50:07+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/","name":"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1","datePublished":"2025-05-16T12:50:07+00:00","dateModified":"2025-05-16T12:50:07+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/colombia-radica-formalmente-en-china-solicitud-de-ingreso-al-banco-de-los-brics\/internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Colombia radica formalmente en China solicitud de ingreso al banco de los BRICS"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/05\/3-2025-05-16T074857.971.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-9ha","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/35660"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=35660"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/35660\/revisions"}],"predecessor-version":[{"id":35662,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/35660\/revisions\/35662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/35661"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=35660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=35660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=35660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}