{"id":33817,"date":"2025-04-16T05:50:16","date_gmt":"2025-04-16T10:50:16","guid":{"rendered":"https:\/\/ciudadyregion.com.co\/?p=33817"},"modified":"2025-04-16T05:50:16","modified_gmt":"2025-04-16T10:50:16","slug":"esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional","status":"publish","type":"post","link":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/","title":{"rendered":"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional"},"content":{"rendered":"<div>El presidente de la Rep\u00fablica, Gustavo Petro Urrego, dio a conocer este martes la terna para la elecci\u00f3n de la nueva magistrada o nuevo magistrado de la Corte Constitucional, en reemplazo de Cristina Pardo Schlesinger.<\/div>\n<div><\/div>\n<div>El anuncio lo hizo el jefe de Estado, a trav\u00e9s de su cuenta de la red social X: \u201cHe decidido presentar la siguiente terna para que el senado escoja magistrada o magistrado que integre la Corte Constitucional: Karena Caselles Hern\u00e1ndez, D\u00eddima Rico Chavarro y H\u00e9ctor Alfonso Carvajal Londo\u00f1o\u201d.<\/div>\n<div><\/div>\n<h2>Karena Caselles Hern\u00e1ndez<\/h2>\n<div><\/div>\n<div>Naci\u00f3 en Villavicencio (Meta), es abogada de la Universidad Santo Tom\u00e1s, especializada en derecho constitucional y en derecho administrativo de la Universidad del Rosario. Tiene un magister en Derecho con \u00e9nfasis en derecho del trabajo de la Universidad Externado. Es su hoja de vida registra con especializaci\u00f3n en derecho constitucional iberoamericano del Instituto de Altos Estudios Judiciales. Curso de Especializaci\u00f3n de Expertos Latinoamericanos en Relaciones Laborales de la Universidad de Castilla &#8211; La Mancha y la Universidad de Bolonia. Es doctorada en derecho de la Universidad Complutense de Madrid.<\/div>\n<div><\/div>\n<div>Fue magistrada encargada de la Corte Constitucional y magistrada auxiliar de la misma corporaci\u00f3n.\u00a0 En su trayectoria profesional tambi\u00e9n trabaj\u00f3 en la Corte Suprema de Justicia como abogada asistente y magistrada auxiliar de la Sala de Casaci\u00f3n Laboral y, adem\u00e1s, fue juez de la Rep\u00fablica. Asimismo, ha ejercido la docencia en la Universidad de Los Andes, Libre de Pereira, de Nari\u00f1o y la Universidad ICESI de Cali.<\/div>\n<div><\/div>\n<h2>D\u00eddima Rico Chavarro<\/h2>\n<div><\/div>\n<div>Ha sido magistrada auxiliar de la Jurisdicci\u00f3n Especial para la Paz (JEP); directora de la Maestr\u00eda en Ciencias Penales y Forenses de la Universidad Aut\u00f3noma de Colombia, editora de la revista Criterio Jur\u00eddico Garantista, adem\u00e1s, autora de art\u00edculos en revistas indexadas.<\/div>\n<div><\/div>\n<div>Asimismo, ha sido profesora de filosof\u00eda de las ciencias penales y forenses, de Derecho penal general y derechos humanos. Tambi\u00e9n se ha desempe\u00f1ado como investigadora y consultora en derechos humanos y cultura de paz. Rico es doctora en Derechos Fundamentales de la Universidad Carlos III de Madrid y especialista en Derecho Penal Universidad Nacional de Colombia.<\/div>\n<div><\/div>\n<h2>H\u00e9ctor Alfonso Carvajal<\/h2>\n<div><\/div>\n<div>El jurista es oriundo de Bogot\u00e1, se desempe\u00f1\u00f3 como fiscal Delegado ante el Tribunal Superior de Bogot\u00e1, asesor del Ministerio de Justicia y Conjuez. Carvajal es especialista en Derecho procesal civil y tambi\u00e9n es abogado especialista en Derecho Administrativo de la Universidad Militar Nueva Granaba. Tambi\u00e9n cuenta con un magister en Derecho P\u00fablico. El postulado es socio fundador de la firma Carvajal Londo\u00f1o y ha trabajado como consultor.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica, Gustavo Petro Urrego, dio a conocer este martes la terna para la elecci\u00f3n de la nueva magistrada o nuevo magistrado de la Corte Constitucional, en reemplazo de Cristina Pardo Schlesinger. El anuncio lo hizo el jefe de Estado, a trav\u00e9s de su cuenta de la<span class=\"more-link\"><a href=\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\">Continuar Leyendo<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":33818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["entry","author-diegoaguirre","post-33817","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region\" \/>\n<meta property=\"og:description\" content=\"El presidente de la Rep\u00fablica, Gustavo Petro Urrego, dio a conocer este martes la terna para la elecci\u00f3n de la nueva magistrada o nuevo magistrado de la Corte Constitucional, en reemplazo de Cristina Pardo Schlesinger. El anuncio lo hizo el jefe de Estado, a trav\u00e9s de su cuenta de laContinuar Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad y Region\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T10:50:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Andr\u00e9s Aguirre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Andr\u00e9s Aguirre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\",\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\",\"name\":\"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region\",\"isPartOf\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1\",\"datePublished\":\"2025-04-16T10:50:16+00:00\",\"dateModified\":\"2025-04-16T10:50:16+00:00\",\"author\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\"},\"breadcrumb\":{\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ciudadyregion.com.co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#website\",\"url\":\"https:\/\/ciudadyregion.com.co\/\",\"name\":\"Ciudad y Region\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ciudadyregion.com.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622\",\"name\":\"David Andr\u00e9s Aguirre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g\",\"caption\":\"David Andr\u00e9s Aguirre\"},\"url\":\"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/","og_locale":"es_ES","og_type":"article","og_title":"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region","og_description":"El presidente de la Rep\u00fablica, Gustavo Petro Urrego, dio a conocer este martes la terna para la elecci\u00f3n de la nueva magistrada o nuevo magistrado de la Corte Constitucional, en reemplazo de Cristina Pardo Schlesinger. El anuncio lo hizo el jefe de Estado, a trav\u00e9s de su cuenta de laContinuar Leyendo","og_url":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/","og_site_name":"Ciudad y Region","article_published_time":"2025-04-16T10:50:16+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg","type":"image\/jpeg"}],"author":"David Andr\u00e9s Aguirre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Andr\u00e9s Aguirre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/","url":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/","name":"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional - Ciudad y Region","isPartOf":{"@id":"https:\/\/ciudadyregion.com.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage"},"image":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1","datePublished":"2025-04-16T10:50:16+00:00","dateModified":"2025-04-16T10:50:16+00:00","author":{"@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622"},"breadcrumb":{"@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#primaryimage","url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/ciudadyregion.com.co\/index.php\/esta-es-la-terna-que-presento-gustavo-petro-para-la-eleccion-de-nuevo-magistrado-de-la-corte-constitucional\/politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ciudadyregion.com.co\/"},{"@type":"ListItem","position":2,"name":"Esta es la terna que present\u00f3 Gustavo Petro para la elecci\u00f3n de nuevo magistrado de la Corte Constitucional"}]},{"@type":"WebSite","@id":"https:\/\/ciudadyregion.com.co\/#website","url":"https:\/\/ciudadyregion.com.co\/","name":"Ciudad y Region","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciudadyregion.com.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/04a4954373ebc4051f46e8c65ff78622","name":"David Andr\u00e9s Aguirre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ciudadyregion.com.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3c655860202182ee6d1b5edd042dbe?s=96&d=mm&r=g","caption":"David Andr\u00e9s Aguirre"},"url":"https:\/\/ciudadyregion.com.co\/index.php\/author\/diegoaguirre\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ciudadyregion.com.co\/wp-content\/uploads\/2025\/04\/2-1-2.jpg?fit=800%2C445&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbS7hh-8Nr","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/33817"}],"collection":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=33817"}],"version-history":[{"count":1,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/33817\/revisions"}],"predecessor-version":[{"id":33819,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/posts\/33817\/revisions\/33819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media\/33818"}],"wp:attachment":[{"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=33817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=33817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ciudadyregion.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=33817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}